{"id":630,"date":"2025-12-30T23:28:21","date_gmt":"2025-12-30T21:28:21","guid":{"rendered":"https:\/\/ildika.com\/dresses\/amina\/"},"modified":"2026-01-09T21:12:17","modified_gmt":"2026-01-09T19:12:17","slug":"amina","status":"publish","type":"dresses","link":"https:\/\/ildika.com\/ua\/dresses\/amina\/","title":{"rendered":"\u0410\u041c\u0406\u041d\u0410"},"featured_media":631,"parent":0,"template":"","dress_collection":[5],"dress_label":[],"class_list":["post-630","dresses","type-dresses","status-publish","has-post-thumbnail","hentry","dress_collection-luminous"],"acf":[],"_links":{"self":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses\/630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses"}],"about":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/types\/dresses"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media\/631"}],"wp:attachment":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media?parent=630"}],"wp:term":[{"taxonomy":"dress_collection","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_collection?post=630"},{"taxonomy":"dress_label","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_label?post=630"}],"curies":[{"name":"\u0412\u041f","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}