{"id":1975,"date":"2026-01-09T17:40:44","date_gmt":"2026-01-09T15:40:44","guid":{"rendered":"https:\/\/ildika.com\/dresses\/jessica\/"},"modified":"2026-01-09T19:17:20","modified_gmt":"2026-01-09T17:17:20","slug":"jessica","status":"publish","type":"dresses","link":"https:\/\/ildika.com\/ua\/dresses\/jessica\/","title":{"rendered":"\u0414\u0416\u0415\u0421\u0421\u0406\u041a\u0410"},"featured_media":1976,"parent":0,"template":"","dress_collection":[7],"dress_label":[],"class_list":["post-1975","dresses","type-dresses","status-publish","has-post-thumbnail","hentry","dress_collection-fiamma"],"acf":[],"_links":{"self":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses\/1975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses"}],"about":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/types\/dresses"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media\/1976"}],"wp:attachment":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media?parent=1975"}],"wp:term":[{"taxonomy":"dress_collection","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_collection?post=1975"},{"taxonomy":"dress_label","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_label?post=1975"}],"curies":[{"name":"\u0412\u041f","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}