{"id":1918,"date":"2026-01-09T17:39:44","date_gmt":"2026-01-09T15:39:44","guid":{"rendered":"https:\/\/ildika.com\/dresses\/nadine\/"},"modified":"2026-01-09T19:17:15","modified_gmt":"2026-01-09T17:17:15","slug":"nadine","status":"publish","type":"dresses","link":"https:\/\/ildika.com\/ua\/dresses\/nadine\/","title":{"rendered":"\u041d\u0410\u0414\u0406\u041d"},"featured_media":1919,"parent":0,"template":"","dress_collection":[7],"dress_label":[],"class_list":["post-1918","dresses","type-dresses","status-publish","has-post-thumbnail","hentry","dress_collection-fiamma"],"acf":[],"_links":{"self":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses\/1918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses"}],"about":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/types\/dresses"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media\/1919"}],"wp:attachment":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media?parent=1918"}],"wp:term":[{"taxonomy":"dress_collection","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_collection?post=1918"},{"taxonomy":"dress_label","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_label?post=1918"}],"curies":[{"name":"\u0412\u041f","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}