{"id":1849,"date":"2026-01-09T17:37:45","date_gmt":"2026-01-09T15:37:45","guid":{"rendered":"https:\/\/ildika.com\/dresses\/emily\/"},"modified":"2026-01-09T19:17:10","modified_gmt":"2026-01-09T17:17:10","slug":"emily","status":"publish","type":"dresses","link":"https:\/\/ildika.com\/ua\/dresses\/emily\/","title":{"rendered":"\u0415\u041c\u0406\u041b\u0406"},"featured_media":1851,"parent":0,"template":"","dress_collection":[7],"dress_label":[],"class_list":["post-1849","dresses","type-dresses","status-publish","has-post-thumbnail","hentry","dress_collection-fiamma"],"acf":[],"_links":{"self":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses\/1849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dresses"}],"about":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/types\/dresses"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media\/1851"}],"wp:attachment":[{"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/media?parent=1849"}],"wp:term":[{"taxonomy":"dress_collection","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_collection?post=1849"},{"taxonomy":"dress_label","embeddable":true,"href":"https:\/\/ildika.com\/ua\/wp-json\/wp\/v2\/dress_label?post=1849"}],"curies":[{"name":"\u0412\u041f","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}